{"id":265692,"date":"2023-08-24T03:54:56","date_gmt":"2023-08-23T23:54:56","guid":{"rendered":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/"},"modified":"2023-08-24T03:54:56","modified_gmt":"2023-08-23T23:54:56","slug":"thiruvananthapuram-to-colombo-flights-booking","status":"publish","type":"cheap-flights","link":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/","title":{"rendered":"Thiruvananthapuram to Colombo Flights Booking"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","categories":[],"class_list":["post-265692","cheap-flights","type-cheap-flights","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Thiruvananthapuram to Colombo Flights Online Booking - Cheap Airfares<\/title>\n<meta name=\"description\" content=\"Book Cheap Thiruvananthapuram to Colombo Flights - Save Big on Your Travel! Find popular Airlines, time, schedule. Cheapest airfare guaranteed on Thiruvananthapuram to Colombo deals\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thiruvananthapuram to Colombo Flights Online Booking - Cheap Airfares\" \/>\n<meta property=\"og:description\" content=\"Book Cheap Thiruvananthapuram to Colombo Flights - Save Big on Your Travel! Find popular Airlines, time, schedule. Cheapest airfare guaranteed on Thiruvananthapuram to Colombo deals\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/\" \/>\n<meta property=\"og:site_name\" content=\"Akbartravels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/\",\"url\":\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/\",\"name\":\"Thiruvananthapuram to Colombo Flights Online Booking - Cheap Airfares\",\"isPartOf\":{\"@id\":\"https:\/\/www.akbartravels.com\/sa\/#website\"},\"datePublished\":\"2023-08-23T23:54:56+00:00\",\"dateModified\":\"2023-08-23T23:54:56+00:00\",\"description\":\"Book Cheap Thiruvananthapuram to Colombo Flights - Save Big on Your Travel! Find popular Airlines, time, schedule. Cheapest airfare guaranteed on Thiruvananthapuram to Colombo deals\",\"breadcrumb\":{\"@id\":\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.akbartravels.com\/sa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cheap Flights\",\"item\":\"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Thiruvananthapuram to Colombo Flights Booking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.akbartravels.com\/sa\/#website\",\"url\":\"https:\/\/www.akbartravels.com\/sa\/\",\"name\":\"Akbartravels\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.akbartravels.com\/sa\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thiruvananthapuram to Colombo Flights Online Booking - Cheap Airfares","description":"Book Cheap Thiruvananthapuram to Colombo Flights - Save Big on Your Travel! Find popular Airlines, time, schedule. Cheapest airfare guaranteed on Thiruvananthapuram to Colombo deals","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/","og_locale":"en_US","og_type":"article","og_title":"Thiruvananthapuram to Colombo Flights Online Booking - Cheap Airfares","og_description":"Book Cheap Thiruvananthapuram to Colombo Flights - Save Big on Your Travel! Find popular Airlines, time, schedule. Cheapest airfare guaranteed on Thiruvananthapuram to Colombo deals","og_url":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/","og_site_name":"Akbartravels","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/","url":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/","name":"Thiruvananthapuram to Colombo Flights Online Booking - Cheap Airfares","isPartOf":{"@id":"https:\/\/www.akbartravels.com\/sa\/#website"},"datePublished":"2023-08-23T23:54:56+00:00","dateModified":"2023-08-23T23:54:56+00:00","description":"Book Cheap Thiruvananthapuram to Colombo Flights - Save Big on Your Travel! Find popular Airlines, time, schedule. Cheapest airfare guaranteed on Thiruvananthapuram to Colombo deals","breadcrumb":{"@id":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/thiruvananthapuram-to-colombo-flights-booking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.akbartravels.com\/sa\/"},{"@type":"ListItem","position":2,"name":"Cheap Flights","item":"https:\/\/www.akbartravels.com\/sa\/cheap-flights\/"},{"@type":"ListItem","position":3,"name":"Thiruvananthapuram to Colombo Flights Booking"}]},{"@type":"WebSite","@id":"https:\/\/www.akbartravels.com\/sa\/#website","url":"https:\/\/www.akbartravels.com\/sa\/","name":"Akbartravels","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.akbartravels.com\/sa\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/cheap-flights\/265692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/cheap-flights"}],"about":[{"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/types\/cheap-flights"}],"author":[{"embeddable":true,"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/comments?post=265692"}],"version-history":[{"count":0,"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/cheap-flights\/265692\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/media?parent=265692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.akbartravels.com\/sa\/wp-json\/wp\/v2\/categories?post=265692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}