{"id":170640,"date":"2024-03-14T13:10:24","date_gmt":"2024-03-14T09:10:24","guid":{"rendered":"https:\/\/b2cbeta.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/"},"modified":"2024-03-14T13:10:24","modified_gmt":"2024-03-14T09:10:24","slug":"vienna-to-mumbai-flights-booking","status":"publish","type":"cheap-flights","link":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/","title":{"rendered":"Vienna to Mumbai Flights Booking"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","categories":[77],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vienna to Mumbai Flights, Cheap Air Tickets from Vienna to Mumbai<\/title>\n<meta name=\"description\" content=\"Book cheap flight tickets from Vienna to Mumbai. Unlock incredible deals for flights from Vienna to Mumbai! Explore unbeatable offers and discounts now\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vienna to Mumbai Flights, Cheap Air Tickets from Vienna to Mumbai\" \/>\n<meta property=\"og:description\" content=\"Book cheap flight tickets from Vienna to Mumbai. Unlock incredible deals for flights from Vienna to Mumbai! Explore unbeatable offers and discounts now\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/\" \/>\n<meta property=\"og:site_name\" content=\"Akbar travels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/\",\"url\":\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/\",\"name\":\"Vienna to Mumbai Flights, Cheap Air Tickets from Vienna to Mumbai\",\"isPartOf\":{\"@id\":\"https:\/\/www.akbartravels.com\/ae\/#website\"},\"datePublished\":\"2024-03-14T09:10:24+00:00\",\"dateModified\":\"2024-03-14T09:10:24+00:00\",\"description\":\"Book cheap flight tickets from Vienna to Mumbai. Unlock incredible deals for flights from Vienna to Mumbai! Explore unbeatable offers and discounts now\",\"breadcrumb\":{\"@id\":\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.akbartravels.com\/ae\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cheap Flights\",\"item\":\"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vienna to Mumbai Flights Booking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.akbartravels.com\/ae\/#website\",\"url\":\"https:\/\/www.akbartravels.com\/ae\/\",\"name\":\"akbartravels.com\/ae\/\",\"description\":\"Akbar travels\",\"publisher\":{\"@id\":\"https:\/\/www.akbartravels.com\/ae\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.akbartravels.com\/ae\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.akbartravels.com\/ae\/#organization\",\"name\":\"akbartravels\",\"url\":\"https:\/\/www.akbartravels.com\/ae\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.akbartravels.com\/ae\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.akbartravels.com\/ae\/wordpress\/wp-content\/uploads\/2023\/08\/Flat-logo-02.png\",\"contentUrl\":\"https:\/\/www.akbartravels.com\/ae\/wordpress\/wp-content\/uploads\/2023\/08\/Flat-logo-02.png\",\"width\":3508,\"height\":999,\"caption\":\"akbartravels\"},\"image\":{\"@id\":\"https:\/\/www.akbartravels.com\/ae\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vienna to Mumbai Flights, Cheap Air Tickets from Vienna to Mumbai","description":"Book cheap flight tickets from Vienna to Mumbai. Unlock incredible deals for flights from Vienna to Mumbai! Explore unbeatable offers and discounts now","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/","og_locale":"en_US","og_type":"article","og_title":"Vienna to Mumbai Flights, Cheap Air Tickets from Vienna to Mumbai","og_description":"Book cheap flight tickets from Vienna to Mumbai. Unlock incredible deals for flights from Vienna to Mumbai! Explore unbeatable offers and discounts now","og_url":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/","og_site_name":"Akbar travels","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/","url":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/","name":"Vienna to Mumbai Flights, Cheap Air Tickets from Vienna to Mumbai","isPartOf":{"@id":"https:\/\/www.akbartravels.com\/ae\/#website"},"datePublished":"2024-03-14T09:10:24+00:00","dateModified":"2024-03-14T09:10:24+00:00","description":"Book cheap flight tickets from Vienna to Mumbai. Unlock incredible deals for flights from Vienna to Mumbai! Explore unbeatable offers and discounts now","breadcrumb":{"@id":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/vienna-to-mumbai-flights-booking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.akbartravels.com\/ae\/"},{"@type":"ListItem","position":2,"name":"Cheap Flights","item":"https:\/\/www.akbartravels.com\/ae\/cheap-flights\/"},{"@type":"ListItem","position":3,"name":"Vienna to Mumbai Flights Booking"}]},{"@type":"WebSite","@id":"https:\/\/www.akbartravels.com\/ae\/#website","url":"https:\/\/www.akbartravels.com\/ae\/","name":"akbartravels.com\/ae\/","description":"Akbar travels","publisher":{"@id":"https:\/\/www.akbartravels.com\/ae\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.akbartravels.com\/ae\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.akbartravels.com\/ae\/#organization","name":"akbartravels","url":"https:\/\/www.akbartravels.com\/ae\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.akbartravels.com\/ae\/#\/schema\/logo\/image\/","url":"https:\/\/www.akbartravels.com\/ae\/wordpress\/wp-content\/uploads\/2023\/08\/Flat-logo-02.png","contentUrl":"https:\/\/www.akbartravels.com\/ae\/wordpress\/wp-content\/uploads\/2023\/08\/Flat-logo-02.png","width":3508,"height":999,"caption":"akbartravels"},"image":{"@id":"https:\/\/www.akbartravels.com\/ae\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/cheap-flights\/170640"}],"collection":[{"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/cheap-flights"}],"about":[{"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/types\/cheap-flights"}],"author":[{"embeddable":true,"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/comments?post=170640"}],"version-history":[{"count":0,"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/cheap-flights\/170640\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/media?parent=170640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.akbartravels.com\/ae\/wp-json\/wp\/v2\/categories?post=170640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}